{"id":7247,"date":"2017-11-27T00:00:00","date_gmt":"2017-11-27T00:00:00","guid":{"rendered":"https:\/\/www.posestacio.com.br\/?p=5419"},"modified":"2023-06-20T15:46:25","modified_gmt":"2023-06-20T18:46:25","slug":"mais-de-500-mil-estudantes-concluram-a-prova-do-enade","status":"publish","type":"post","link":"https:\/\/www.graduacaobr.com.br\/estacio\/mais-de-500-mil-estudantes-concluram-a-prova-do-enade\/","title":{"rendered":"Mais de 500 mil estudantes conclu\u00edram a prova do Enade"},"content":{"rendered":"\n<div>\r\n\tNeste domingo (26), 537.407 estudantes realizaram as provas do Exame Nacional de Desempenho de Estudantes (Enade) 2017. O exame avalia a qualidade dos cursos por meio do desempenho acad&ecirc;mico dos estudantes em rela&ccedil;&atilde;o aos conte&uacute;dos previstos nas diretrizes curriculares, bem como o processo de aprendizagem.<\/div>\r\n<div>\r\n\t&nbsp;<\/div>\r\n<div>\r\n\tA avalia&ccedil;&atilde;o aplicada neste domingo come&ccedil;ou no in&iacute;cio da tarde e os inscritos tiveram 4 horas para responder a 40 quest&otilde;es. Dez das quest&otilde;es aplicadas s&atilde;o da parte de forma&ccedil;&atilde;o geral e 30 de forma&ccedil;&atilde;o espec&iacute;fica da &aacute;rea que estudam, com quest&otilde;es discursivas e de m&uacute;ltipla escolha.<\/div>\r\n<div>\r\n\t&nbsp;<\/div>\r\n<div>\r\n\tDas 10 quest&otilde;es do Componente de Forma&ccedil;&atilde;o Geral, duas s&atilde;o discursivas e oito de m&uacute;ltipla escolha, envolvendo situa&ccedil;&otilde;es-problema e estudos de casos. J&aacute; o componente espec&iacute;fico de cada &aacute;rea ou Curso Superior de Tecnologia tem 30 quest&otilde;es, sendo tr&ecirc;s discursivas e 27 de m&uacute;ltipla escolha, envolvendo situa&ccedil;&otilde;es-problema e estudo de casos.<\/div>\r\n<div>\r\n\t&nbsp;<\/div>\r\n<div>\r\n\tPerfil<\/div>\r\n<div>\r\n\t&nbsp;<\/div>\r\n<div>\r\n\tUm dos instrumentos de coleta de informa&ccedil;&otilde;es do Enade, o preenchimento do Question&aacute;rio do Estudante &eacute; obrigat&oacute;rio. Seu objetivo &eacute; subsidiar a constru&ccedil;&atilde;o do perfil socioecon&ocirc;mico do estudante e obter uma aprecia&ccedil;&atilde;o quanto ao seu processo formativo. O documento ficou dispon&iacute;vel de 4 de setembro at&eacute; este domingo, data da aplica&ccedil;&atilde;o.<\/div>\r\n<div>\r\n\t&nbsp;<\/div>\r\n<div>\r\n\tO Enade &eacute; um dos instrumentos do Sistema Nacional de Avalia&ccedil;&atilde;o da Educa&ccedil;&atilde;o Superior (Sinaes). O exame tamb&eacute;m contribui para a constru&ccedil;&atilde;o de indicadores de qualidade da educa&ccedil;&atilde;o superior, como o conceito Enade, o conceito preliminar de curso (CPC) e o &iacute;ndice geral de cursos (IGC).<\/div>\r\n\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo (26), 537.407 estudantes realizaram as provas do Exame Nacional de Desempenho de Estudantes (Enade) 2017. O exame avalia a qualidade dos cursos por meio do desempenho acad&ecirc;mico dos estudantes em rela&ccedil;&atilde;o aos conte&uacute;dos previstos nas diretrizes curriculares, bem como o processo de aprendizagem. &nbsp; A avalia&ccedil;&atilde;o aplicada neste domingo come&ccedil;ou no in&iacute;cio da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7249,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/posts\/7247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/comments?post=7247"}],"version-history":[{"count":0,"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/posts\/7247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/media\/7249"}],"wp:attachment":[{"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/media?parent=7247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/categories?post=7247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.graduacaobr.com.br\/estacio\/wp-json\/wp\/v2\/tags?post=7247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}